{"id":5880,"date":"2019-07-30T19:40:56","date_gmt":"2019-07-30T18:40:56","guid":{"rendered":"http:\/\/ptiket.eu\/?p=5880"},"modified":"2021-04-14T09:51:30","modified_gmt":"2021-04-14T08:51:30","slug":"british-columbia-yukon","status":"publish","type":"post","link":"https:\/\/ptiket.eu\/index.php\/2019\/07\/30\/british-columbia-yukon\/","title":{"rendered":"British Columbia &#8211; Yukon"},"content":{"rendered":"\n<p>Le soleil est revenu et le vent aussi. \u00c7a va augmenter un peu notre consommation mais les points de fourniture de carburant ne sont pas espac\u00e9s de plus de 200km pour l\u2019instant. Nous n\u2019utilisons pas encore le bidon de r\u00e9serve.&nbsp;<\/p>\n\n\n\n<ul data-carousel-extra='{\"blog_id\":1,\"permalink\":\"https:\\\/\\\/ptiket.eu\\\/index.php\\\/2019\\\/07\\\/30\\\/british-columbia-yukon\\\/\"}' class=\"wp-block-gallery aligncenter columns-3 is-cropped wp-block-gallery-1 is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321-1024x768.jpeg\"><img data-attachment-id=\"5860\" data-permalink=\"https:\/\/ptiket.eu\/7be4dccc-5428-4cb6-b167-6efe7f121321\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?fit=2070%2C1553&amp;ssl=1\" data-orig-size=\"2070,1553\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"7BE4DCCC-5428-4CB6-B167-6EFE7F121321\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321-1024x768.jpeg?resize=768%2C576\" alt=\"\" data-id=\"5860\" data-link=\"http:\/\/ptiket.eu\/7be4dccc-5428-4cb6-b167-6efe7f121321\/\" class=\"wp-image-5860\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7BE4DCCC-5428-4CB6-B167-6EFE7F121321.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148-1024x768.jpeg\"><img data-attachment-id=\"5861\" data-permalink=\"https:\/\/ptiket.eu\/6f20fbbe-472a-4ea9-ab3a-d5597852c148\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"6F20FBBE-472A-4EA9-AB3A-D5597852C148\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148-1024x768.jpeg?resize=768%2C576\" alt=\"\" data-id=\"5861\" data-link=\"http:\/\/ptiket.eu\/6f20fbbe-472a-4ea9-ab3a-d5597852c148\/\" class=\"wp-image-5861\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/6F20FBBE-472A-4EA9-AB3A-D5597852C148.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC-1024x735.jpeg\"><img data-attachment-id=\"5862\" data-permalink=\"https:\/\/ptiket.eu\/43a2eb43-dab3-4ae8-9d15-377f6e83d3ec\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?fit=4354%2C3124&amp;ssl=1\" data-orig-size=\"4354,3124\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?fit=300%2C215&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?fit=768%2C551&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"551\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC-1024x735.jpeg?resize=768%2C551\" alt=\"\" data-id=\"5862\" data-link=\"http:\/\/ptiket.eu\/43a2eb43-dab3-4ae8-9d15-377f6e83d3ec\/\" class=\"wp-image-5862\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?resize=1024%2C735&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?resize=300%2C215&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?resize=768%2C551&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/43A2EB43-DAB3-4AE8-9D15-377F6E83D3EC.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26-1024x768.jpeg\"><img data-attachment-id=\"5864\" data-permalink=\"https:\/\/ptiket.eu\/3be74294-6daf-4822-be21-9c4b44bdcc26\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3BE74294-6DAF-4822-BE21-9C4B44BDCC26\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26-1024x768.jpeg?resize=768%2C576\" alt=\"\" data-id=\"5864\" data-link=\"http:\/\/ptiket.eu\/3be74294-6daf-4822-be21-9c4b44bdcc26\/\" class=\"wp-image-5864\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3BE74294-6DAF-4822-BE21-9C4B44BDCC26.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2-1024x768.jpeg\"><img data-attachment-id=\"5865\" data-permalink=\"https:\/\/ptiket.eu\/13b5bd48-b444-41a9-8ce5-d8916d8886c2\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"13B5BD48-B444-41A9-8CE5-D8916D8886C2\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2-1024x768.jpeg?resize=768%2C576\" alt=\"\" data-id=\"5865\" data-link=\"http:\/\/ptiket.eu\/13b5bd48-b444-41a9-8ce5-d8916d8886c2\/\" class=\"wp-image-5865\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/13B5BD48-B444-41A9-8CE5-D8916D8886C2.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><\/ul>\n\n\n\n<p>Nous avons fait d\u2019incroyables rencontres ces derniers jours et toujours dans des endroits improbables. Des Br\u00e9siliens et un Canadien coinc\u00e9s dans un camping en attendant des pi\u00e8ces pour leurs motos, des Qu\u00e9b\u00e9cois qui connaissent un Suisse qui voyage en Acadiane, un jeune couple de Dr\u00f4mois qui voyagent \u00e0 v\u00e9lo, des bikers argentins et colombiens qui font le tour du monde (quel plaisir de les entendre parler), un jeune couple de Fran\u00e7ais qui pense s\u2019installer au Canada.<\/p>\n\n\n\n<p>Certains reviennent de Tuktoyaktuk et nous indiquent dans quel \u00e9tat est la route jusque l\u00e0 haut. \u00c7a devrait le faire. Les autres, nous les recroiserons s\u00fbrement un jour ou l\u2019autre.<\/p>\n\n\n\n<p>Ah oui, un ours et un renard !<\/p>\n\n\n\n<div data-carousel-extra='{\"blog_id\":1,\"permalink\":\"https:\\\/\\\/ptiket.eu\\\/index.php\\\/2019\\\/07\\\/30\\\/british-columbia-yukon\\\/\"}' class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg\"><img data-attachment-id=\"5870\" data-permalink=\"https:\/\/ptiket.eu\/c71e7d2c-4cde-47e8-be98-d58ac0c110e5\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?fit=561%2C561&amp;ssl=1\" data-orig-size=\"561,561\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?fit=300%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?fit=561%2C561&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"561\" height=\"561\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?resize=561%2C561\" alt=\"\" class=\"wp-image-5870\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?w=561&amp;ssl=1 561w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?resize=176%2C176&amp;ssl=1 176w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C71E7D2C-4CDE-47E8-BE98-D58AC0C110E5.jpeg?resize=300%2C300&amp;ssl=1 300w\" sizes=\"(max-width: 561px) 100vw, 561px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/div>\n\n\n\n<p>Au bout de la highway 37, c\u2019est le Yukon, plus grand que nature !<br><\/p>\n\n\n\n<ul data-carousel-extra='{\"blog_id\":1,\"permalink\":\"https:\\\/\\\/ptiket.eu\\\/index.php\\\/2019\\\/07\\\/30\\\/british-columbia-yukon\\\/\"}' class=\"wp-block-gallery aligncenter columns-3 is-cropped wp-block-gallery-3 is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A-1024x684.jpeg\"><img data-attachment-id=\"5873\" data-permalink=\"https:\/\/ptiket.eu\/948c3243-6508-4a1f-968a-5703cfdfca0a\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"948C3243-6508-4A1F-968A-5703CFDFCA0A\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"513\" src=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A-1024x684.jpeg?resize=768%2C513\" alt=\"\" data-id=\"5873\" data-link=\"http:\/\/ptiket.eu\/948c3243-6508-4a1f-968a-5703cfdfca0a\/\" class=\"wp-image-5873\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/948C3243-6508-4A1F-968A-5703CFDFCA0A.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC-1024x684.jpeg\"><img data-attachment-id=\"5874\" data-permalink=\"https:\/\/ptiket.eu\/c498276d-f3d4-41cf-aec2-4a9a73a14afc\/\" data-orig-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"C498276D-F3D4-41CF-AEC2-4A9A73A14AFC\" data-image-description=\"\" data-medium-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"513\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC-1024x684.jpeg?resize=768%2C513\" alt=\"\" data-id=\"5874\" data-link=\"http:\/\/ptiket.eu\/c498276d-f3d4-41cf-aec2-4a9a73a14afc\/\" class=\"wp-image-5874\" srcset=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/C498276D-F3D4-41CF-AEC2-4A9A73A14AFC.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF-1024x768.jpeg\"><img data-attachment-id=\"5875\" data-permalink=\"https:\/\/ptiket.eu\/edff0a3a-248b-463f-ae59-48a3997182ff\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"EDFF0A3A-248B-463F-AE59-48A3997182FF\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF-1024x768.jpeg?resize=768%2C576\" alt=\"\" data-id=\"5875\" data-link=\"http:\/\/ptiket.eu\/edff0a3a-248b-463f-ae59-48a3997182ff\/\" class=\"wp-image-5875\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/EDFF0A3A-248B-463F-AE59-48A3997182FF.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84-1024x684.jpeg\"><img data-attachment-id=\"5876\" data-permalink=\"https:\/\/ptiket.eu\/3b218129-d850-479e-aca6-72fe38d2fe84\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3B218129-D850-479E-ACA6-72FE38D2FE84\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"513\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84-1024x684.jpeg?resize=768%2C513\" alt=\"\" data-id=\"5876\" data-link=\"http:\/\/ptiket.eu\/3b218129-d850-479e-aca6-72fe38d2fe84\/\" class=\"wp-image-5876\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/3B218129-D850-479E-ACA6-72FE38D2FE84.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359-684x1024.jpeg\"><img data-attachment-id=\"5877\" data-permalink=\"https:\/\/ptiket.eu\/de6cf184-a03f-4a28-9871-856ae931e359\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?fit=1080%2C1616&amp;ssl=1\" data-orig-size=\"1080,1616\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"DE6CF184-A03F-4A28-9871-856AE931E359\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?fit=684%2C1024&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"684\" height=\"1024\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359-684x1024.jpeg?resize=684%2C1024\" alt=\"\" data-id=\"5877\" data-link=\"http:\/\/ptiket.eu\/de6cf184-a03f-4a28-9871-856ae931e359\/\" class=\"wp-image-5877\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?resize=768%2C1149&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/DE6CF184-A03F-4A28-9871-856AE931E359.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"(max-width: 684px) 100vw, 684px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003-1024x768.jpeg\"><img data-attachment-id=\"5878\" data-permalink=\"https:\/\/ptiket.eu\/7b0e2312-e155-4f75-8a9b-f91c0c197003\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?fit=1442%2C1081&amp;ssl=1\" data-orig-size=\"1442,1081\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"7B0E2312-E155-4F75-8A9B-F91C0C197003\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003-1024x768.jpeg?resize=768%2C576\" alt=\"\" data-id=\"5878\" data-link=\"http:\/\/ptiket.eu\/7b0e2312-e155-4f75-8a9b-f91c0c197003\/\" class=\"wp-image-5878\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/7B0E2312-E155-4F75-8A9B-F91C0C197003.jpeg?w=1442&amp;ssl=1 1442w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070-1024x684.jpeg\"><img data-attachment-id=\"5879\" data-permalink=\"https:\/\/ptiket.eu\/5a133f3a-286b-4c43-a918-2cf10dc03070\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"5A133F3A-286B-4C43-A918-2CF10DC03070\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"513\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070-1024x684.jpeg?resize=768%2C513\" alt=\"\" data-id=\"5879\" data-link=\"http:\/\/ptiket.eu\/5a133f3a-286b-4c43-a918-2cf10dc03070\/\" class=\"wp-image-5879\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/07\/5A133F3A-286B-4C43-A918-2CF10DC03070.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Le soleil est revenu et le vent aussi. \u00c7a va augmenter un peu notre consommation mais les points de fourniture de carburant ne sont pas espac\u00e9s de plus de 200km pour l\u2019instant. Nous n\u2019utilisons pas encore le bidon de r\u00e9serve.&nbsp; Nous avons fait d\u2019incroyables rencontres ces derniers jours et toujours dans des endroits improbables. Des [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":""},"categories":[73],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7RS3Q-1wQ","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts\/5880"}],"collection":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/comments?post=5880"}],"version-history":[{"count":8,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts\/5880\/revisions"}],"predecessor-version":[{"id":7025,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts\/5880\/revisions\/7025"}],"wp:attachment":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/media?parent=5880"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/categories?post=5880"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/tags?post=5880"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}