{"id":3841,"date":"2019-02-16T03:13:30","date_gmt":"2019-02-16T02:13:30","guid":{"rendered":"http:\/\/ptiket.eu\/?p=3841"},"modified":"2019-02-16T03:20:28","modified_gmt":"2019-02-16T02:20:28","slug":"jardin","status":"publish","type":"post","link":"https:\/\/ptiket.eu\/index.php\/2019\/02\/16\/jardin\/","title":{"rendered":"Jardin"},"content":{"rendered":"\n<p>La libert\u00e9 du voyage c\u2019est de pouvoir aller un peu vers l\u2019ouest, ou vers l\u2019est et pourquoi pas au sud&nbsp; m\u00eame si notre destination est au nord.<\/p>\n\n\n\n<p>Nous redescendons vers Jardin, petite ville tr\u00e8s fleurie, entour\u00e9e de caf\u00e9iers et de bananiers.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE-792x1024.jpeg\"><img data-attachment-id=\"3826\" data-permalink=\"https:\/\/ptiket.eu\/10c87102-10b5-4a31-a7fb-df59005b69ce\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?fit=1848%2C2390&amp;ssl=1\" data-orig-size=\"1848,2390\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"10C87102-10B5-4A31-A7FB-DF59005B69CE\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?fit=232%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?fit=768%2C993&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"232\" height=\"300\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE-232x300.jpeg?resize=232%2C300\" alt=\"\" class=\"wp-image-3826\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?resize=232%2C300&amp;ssl=1 232w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?resize=768%2C993&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?resize=792%2C1024&amp;ssl=1 792w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?w=1848&amp;ssl=1 1848w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/10C87102-10B5-4A31-A7FB-DF59005B69CE.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 232px) 100vw, 232px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C-1024x768.jpeg\"><img data-attachment-id=\"3827\" data-permalink=\"https:\/\/ptiket.eu\/02cf22bc-cee0-46f8-b481-f91a8a32025c\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?fit=3724%2C2793&amp;ssl=1\" data-orig-size=\"3724,2793\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"02CF22BC-CEE0-46F8-B481-F91A8A32025C\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C-1024x768.jpeg?resize=768%2C576\" alt=\"\" class=\"wp-image-3827\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/02CF22BC-CEE0-46F8-B481-F91A8A32025C.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><figcaption>Notre bivouac<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg\"><img data-attachment-id=\"3825\" data-permalink=\"https:\/\/ptiket.eu\/55ad3b79-6dee-4231-998f-9b69e98f3da6\/\" data-orig-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg?fit=947%2C709&amp;ssl=1\" data-orig-size=\"947,709\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"55AD3B79-6DEE-4231-998F-9B69E98F3DA6\" data-image-description=\"\" data-medium-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg?fit=768%2C575&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" src=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6-300x225.jpeg?resize=300%2C225\" alt=\"\" class=\"wp-image-3825\" srcset=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg?resize=768%2C575&amp;ssl=1 768w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/55AD3B79-6DEE-4231-998F-9B69E98F3DA6.jpeg?w=947&amp;ssl=1 947w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><figcaption>Transport scolaire<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg\"><img data-attachment-id=\"3837\" data-permalink=\"https:\/\/ptiket.eu\/947ffefb-69cf-4de0-9846-916fa49514c6\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?fit=1616%2C830&amp;ssl=1\" data-orig-size=\"1616,830\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"947FFEFB-69CF-4DE0-9846-916FA49514C6\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?fit=300%2C154&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?fit=768%2C395&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"154\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6-300x154.jpeg?resize=300%2C154\" alt=\"\" class=\"wp-image-3837\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?resize=300%2C154&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?resize=768%2C394&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?resize=1024%2C526&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/947FFEFB-69CF-4DE0-9846-916FA49514C6.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><figcaption>Transport public<\/figcaption><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg\"><img data-attachment-id=\"3831\" data-permalink=\"https:\/\/ptiket.eu\/7e15d99f-1a5d-4d9c-9582-fc0e15b24114\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"7E15D99F-1A5D-4D9C-9582-FC0E15B24114\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114-300x200.jpeg?resize=300%2C200\" alt=\"\" class=\"wp-image-3831\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/7E15D99F-1A5D-4D9C-9582-FC0E15B24114.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><figcaption>Des DTMX plein les rues, notre premi\u00e8re moto<\/figcaption><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"alignleft\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg\"><img data-attachment-id=\"3834\" data-permalink=\"https:\/\/ptiket.eu\/30d30a0b-825c-4397-8e15-30982a531658\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"30D30A0B-825C-4397-8E15-30982A531658\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658-300x225.jpeg?resize=300%2C225\" alt=\"\" class=\"wp-image-3834\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/30D30A0B-825C-4397-8E15-30982A531658.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg\"><img data-attachment-id=\"3828\" data-permalink=\"https:\/\/ptiket.eu\/72d940d9-a89b-4557-9d2f-9185cdad4801\/\" data-orig-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"72D940D9-A89B-4557-9D2F-9185CDAD4801\" data-image-description=\"\" data-medium-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" src=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801-300x225.jpeg?resize=300%2C225\" alt=\"\" class=\"wp-image-3828\" srcset=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/72D940D9-A89B-4557-9D2F-9185CDAD4801.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E-1024x684.jpeg\"><img data-attachment-id=\"3829\" data-permalink=\"https:\/\/ptiket.eu\/97361277-4e9a-41dd-81e9-a1314cf8105e\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"97361277-4E9A-41DD-81E9-A1314CF8105E\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E-300x200.jpeg?resize=300%2C200\" alt=\"\" class=\"wp-image-3829\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/97361277-4E9A-41DD-81E9-A1314CF8105E.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg\"><img data-attachment-id=\"3830\" data-permalink=\"https:\/\/ptiket.eu\/e6c1c7b8-d978-4773-8a41-b57c888671ad\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?fit=1493%2C998&amp;ssl=1\" data-orig-size=\"1493,998\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"E6C1C7B8-D978-4773-8A41-B57C888671AD\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?fit=300%2C201&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"201\" src=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD-300x201.jpeg?resize=300%2C201\" alt=\"\" class=\"wp-image-3830\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?resize=300%2C201&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/E6C1C7B8-D978-4773-8A41-B57C888671AD.jpeg?w=1493&amp;ssl=1 1493w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44-1024x684.jpeg\"><img data-attachment-id=\"3832\" data-permalink=\"https:\/\/ptiket.eu\/b07d3a3f-409b-488a-aacd-29c30a4e8a44\/\" data-orig-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?fit=1616%2C1080&amp;ssl=1\" data-orig-size=\"1616,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"B07D3A3F-409B-488A-AACD-29C30A4E8A44\" data-image-description=\"\" data-medium-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?fit=300%2C200&amp;ssl=1\" data-large-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?fit=768%2C513&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44-300x200.jpeg?resize=300%2C200\" alt=\"\" class=\"wp-image-3832\" srcset=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?resize=768%2C513&amp;ssl=1 768w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?resize=1024%2C684&amp;ssl=1 1024w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?w=1616&amp;ssl=1 1616w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/B07D3A3F-409B-488A-AACD-29C30A4E8A44.jpeg?w=1536&amp;ssl=1 1536w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg\"><img data-attachment-id=\"3833\" data-permalink=\"https:\/\/ptiket.eu\/4cfa854b-4d4e-4327-98e5-a6ca79862526\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?fit=885%2C1325&amp;ssl=1\" data-orig-size=\"885,1325\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"4CFA854B-4D4E-4327-98E5-A6CA79862526\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?fit=684%2C1024&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"200\" height=\"300\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526-200x300.jpeg?resize=200%2C300\" alt=\"\" class=\"wp-image-3833\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?resize=768%2C1150&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/4CFA854B-4D4E-4327-98E5-A6CA79862526.jpeg?w=885&amp;ssl=1 885w\" sizes=\"(max-width: 200px) 100vw, 200px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg\"><img data-attachment-id=\"3835\" data-permalink=\"https:\/\/ptiket.eu\/19bd3b8c-06f4-459c-a82b-7a93214d57bd\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"19BD3B8C-06F4-459C-A82B-7A93214D57BD\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD-1024x768.jpeg?resize=768%2C576\" alt=\"\" class=\"wp-image-3835\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/19BD3B8C-06F4-459C-A82B-7A93214D57BD.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg\"><img data-attachment-id=\"3836\" data-permalink=\"https:\/\/ptiket.eu\/76f2cc61-fbf8-43f8-8c73-0659b4e1e678\/\" data-orig-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"76F2CC61-FBF8-43F8-8C73-0659B4E1E678\" data-image-description=\"\" data-medium-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"225\" src=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678-300x225.jpeg?resize=300%2C225\" alt=\"\" class=\"wp-image-3836\" srcset=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/76F2CC61-FBF8-43F8-8C73-0659B4E1E678.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg\"><img data-attachment-id=\"3838\" data-permalink=\"https:\/\/ptiket.eu\/3d9865b6-a188-42cc-b351-cb1e683016f0\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?fit=1080%2C1616&amp;ssl=1\" data-orig-size=\"1080,1616\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"3D9865B6-A188-42CC-B351-CB1E683016F0\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?fit=200%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?fit=684%2C1024&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"684\" height=\"1024\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0-684x1024.jpeg?resize=684%2C1024\" alt=\"\" class=\"wp-image-3838\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?resize=684%2C1024&amp;ssl=1 684w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?resize=200%2C300&amp;ssl=1 200w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?resize=768%2C1149&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/3D9865B6-A188-42CC-B351-CB1E683016F0.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"(max-width: 684px) 100vw, 684px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/div>\n\n\n\n<figure class=\"wp-block-image\"><a href=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg\"><img data-attachment-id=\"3840\" data-permalink=\"https:\/\/ptiket.eu\/d5b4717c-5721-4220-a1bb-17ae4e537f72\/\" data-orig-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?fit=1080%2C1080&amp;ssl=1\" data-orig-size=\"1080,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"D5B4717C-5721-4220-A1BB-17AE4E537F72\" data-image-description=\"\" data-medium-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?fit=300%2C300&amp;ssl=1\" data-large-file=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?fit=768%2C768&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"300\" height=\"300\" src=\"https:\/\/i0.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72-300x300.jpeg?resize=300%2C300\" alt=\"\" class=\"wp-image-3840\" srcset=\"https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?resize=300%2C300&amp;ssl=1 300w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?resize=176%2C176&amp;ssl=1 176w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?resize=768%2C768&amp;ssl=1 768w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?resize=1024%2C1024&amp;ssl=1 1024w, https:\/\/i1.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/D5B4717C-5721-4220-A1BB-17AE4E537F72.jpeg?w=1080&amp;ssl=1 1080w\" sizes=\"(max-width: 300px) 100vw, 300px\" data-recalc-dims=\"1\" \/><\/a><\/figure>\n\n\n\n<p>Tous les villages que nous avons travers\u00e9s jusqu\u2019\u00e0 pr\u00e9sent impressionnent par leur joie de vivre, leurs couleurs vives, leur tranquillit\u00e9 anim\u00e9e. On a du mal \u00e0 imaginer que la gu\u00e9rilla et les trafiquants s\u00e9vissaient encore dans la r\u00e9gion il n\u2019y a pas si longtemps. <\/p>\n\n\n\n<p>Aujourd\u2019hui les habitants et surtout les jeunes ont d\u00e9cid\u00e9 de reprendre leur avenir en main et s\u2019efforcent de pr\u00e9server leur patrimoine naturel et culturel. Ils ont notamment et majoritairement dit non \u00e0 l\u2019exploitation de mines de m\u00e9taux et pierres pr\u00e9cieuses qui auraient pollu\u00e9 et d\u00e9figur\u00e9 l\u2019environnement. Plus difficile \u00e0 maitriser, la d\u00e9forestation syst\u00e9matique pour cr\u00e9er des p\u00e2turages pour le b\u00e9tail ou installer des mono cultures, mettant en danger plusieurs esp\u00e8ces d\u2019animaux et de v\u00e9g\u00e9taux.<\/p>\n\n\n\n<p>Les ca\u00efds de la drogue ont \u00e9t\u00e9 mis hors jeu et si le trafic n\u2019a pas disparu, il se limite maintenant \u00e0 un territoire pr\u00e8s de la c\u00f4te pacifique, officieusement. Quant aux gu\u00e9rilleros, l\u2019implication du pouvoir en place n\u2019est pas tr\u00e8s claire.<\/p>\n\n\n\n<p>Bref, la Colombie est une vraie belle surprise pour nous. En plus on y mange tr\u00e8s bien et on y a retrouv\u00e9 de la vraie bonne viande.<\/p>\n\n\n\n<p>Un double expresso, le soir sur la place principale de Jardin et c\u2019est l\u2019insomnie. Du coup le blog est \u00e0 jour&#8230;<br><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter\"><a href=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg\"><img data-attachment-id=\"3847\" data-permalink=\"https:\/\/ptiket.eu\/0e96bae9-a587-4819-9365-5331a732c377\/\" data-orig-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?fit=3264%2C2448&amp;ssl=1\" data-orig-size=\"3264,2448\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"0E96BAE9-A587-4819-9365-5331A732C377\" data-image-description=\"\" data-medium-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?fit=300%2C225&amp;ssl=1\" data-large-file=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?fit=768%2C576&amp;ssl=1\" decoding=\"async\" loading=\"lazy\" width=\"768\" height=\"576\" src=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452-1024x768.jpeg?resize=768%2C576\" alt=\"\" class=\"wp-image-3847\" srcset=\"https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?resize=1024%2C768&amp;ssl=1 1024w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?resize=300%2C225&amp;ssl=1 300w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?resize=768%2C576&amp;ssl=1 768w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?w=1536&amp;ssl=1 1536w, https:\/\/i2.wp.com\/ptiket.eu\/wp-content\/uploads\/2019\/02\/0E96BAE9-A587-4819-9365-5331A732C377-e1550283558452.jpeg?w=2304&amp;ssl=1 2304w\" sizes=\"(max-width: 768px) 100vw, 768px\" data-recalc-dims=\"1\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>La libert\u00e9 du voyage c\u2019est de pouvoir aller un peu vers l\u2019ouest, ou vers l\u2019est et pourquoi pas au sud&nbsp; m\u00eame si notre destination est au nord. Nous redescendons vers Jardin, petite ville tr\u00e8s fleurie, entour\u00e9e de caf\u00e9iers et de bananiers. Tous les villages que nous avons travers\u00e9s jusqu\u2019\u00e0 pr\u00e9sent impressionnent par leur joie de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":""},"categories":[51,23],"tags":[],"jetpack_featured_media_url":"","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/s7RS3Q-jardin","jetpack-related-posts":[],"_links":{"self":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts\/3841"}],"collection":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/comments?post=3841"}],"version-history":[{"count":5,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts\/3841\/revisions"}],"predecessor-version":[{"id":3848,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/posts\/3841\/revisions\/3848"}],"wp:attachment":[{"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/media?parent=3841"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/categories?post=3841"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ptiket.eu\/index.php\/wp-json\/wp\/v2\/tags?post=3841"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}